{"id":60288,"date":"2022-12-16T14:15:00","date_gmt":"2022-12-16T17:15:00","guid":{"rendered":"https:\/\/prnewswire.com.br\/?post_type=releases&amp;p=55402"},"modified":"2022-12-16T14:15:00","modified_gmt":"2022-12-16T17:15:00","slug":"lista-da-accor-com-as-principais-inauguracoes-de-hoteis-em-2023","status":"publish","type":"post","link":"https:\/\/verde-amarelo.net\/verdeamarelo\/2022\/12\/lista-da-accor-com-as-principais-inauguracoes-de-hoteis-em-2023\/","title":{"rendered":"Lista da Accor com as principais inaugura\u00e7\u00f5es de hot\u00e9is em 2023"},"content":{"rendered":"<div class=\"xn-content\">\n<p><span>UM RESUMO DAS PR\u00d3XIMAS PROPRIEDADES DO PORTF\u00d3LIO MAIS DIVERSO DO MUNDO DE MARCAS HOTELEIRAS<\/span><\/p>\n<p><span class=\"legendSpanClass\">PARIS<\/span>, <span class=\"legendSpanClass\">16 de dezembro de 2022<\/span> <span>- Atualizado -  &#8212; \u00c0 medida que o burburinho e a expectativa aumentam em torno do planejamento de viagens para 2023, a Accor tem o prazer de revelar uma pequena lista de propriedades altamente esperadas para inaugurar no pr\u00f3ximo ano. Da cidade ao litoral, de hot\u00e9is ecol\u00f3gicos ou econ\u00f4micos a ref\u00fagios ultra luxuosos, a lista cont\u00e9m destinos belos e aventureiros que h\u00f3spedes e viajantes do mundo todo estar\u00e3o ansiosos para ver&#8230; e para que sejam vistos neles. Nenhum filtro do TikTok ou do Instagram \u00e9 necess\u00e1rio!<\/span><\/p>\n<p><b><span>HOT\u00c9IS E RESORTS DE LUXO<\/span><\/b>\u00a0<\/p>\n<p><i><span>A Accor \u00e9 l\u00edder global no setor de luxo, tendo curado um dos portf\u00f3lios de luxo mais extraordin\u00e1rios do mundo. As marcas de luxo da Accor s\u00e3o conhecidas n\u00e3o apenas por sua hospitalidade cort\u00eas, atenciosa e personalizada, como tamb\u00e9m por seus restaurantes e bares premiados, programa\u00e7\u00e3o de bem-estar transformadora, e experi\u00eancias personalizadas que abrem mentes, expandem conhecimentos e mudam perspectivas.<\/span><\/i><\/p>\n<p><b><span>Sofitel Legend Casco Viejo Panama (in\u00edcio de 2023)<\/span><\/b><span><br \/><\/br>O primeiro e \u00fanico hotel de luxo no Panam\u00e1 com uma aut\u00eantica identidade francesa, trazendo sua <span class=\"xn-person\">Art de Vivre<\/span> para a cidade hist\u00f3rica de <span class=\"xn-person\">Casco Viejo<\/span>, no Panam\u00e1, que \u00e9 Patrim\u00f4nio Mundial da UNESCO. O Sofitel Legend Casco Viejo Panama ser\u00e1 o sexto endere\u00e7o lend\u00e1rio no prestigioso portf\u00f3lio da marca Sofitel Legend. Constru\u00eddo diretamente na \u00e1gua, com vistas desobstru\u00eddas e impressionantes do Oceano Pac\u00edfico e do horizonte da cidade do Panam\u00e1, o hotel contar\u00e1 com uma combina\u00e7\u00e3o superior de instala\u00e7\u00f5es e comodidades, incluindo 159 quartos e su\u00edtes lindamente decorados, com a grande maioria deles tendo paisagens mar\u00edtimas invej\u00e1veis; cinco pontos espetaculares para comer e beber, incluindo um lounge e bar no terra\u00e7o; uma piscina \u00e0 beira-mar; e aproximadamente 918 mil metros quadrados de espa\u00e7o funcional interno e externo flex\u00edveis.<\/span><\/p>\n<p><b><span>Fairmont Ramla Serviced Residences, Riade (in\u00edcio de 2023)<\/span><\/b><span>O<br \/><\/br>Fairmont Ramla Serviced Residences \u00e9 um destino de luxo ecol\u00f3gico verdadeiramente \u00fanico, que em breve ser\u00e1 o endere\u00e7o residencial mais procurado da capital. Trinta e cinco andares acomodam 249 unidades residenciais espa\u00e7osas e luxuosas, cada uma com terra\u00e7os privativos que oferecem vistas espetaculares da cidade de Riade. O hotel fica bem no centro de tudo, pr\u00f3ximo ao King Abdullah Financial District e ao Riyadh International Convention &#038; Exhibition Center, com f\u00e1cil acesso ao Aeroporto Internacional Rei Khalid.<\/span><\/p>\n<p><b><span>Raffles <span class=\"xn-location\">London<\/span> at The OWO (meados de 2023)<\/span><\/b><span><br \/><\/br>Obra-prima arquitet\u00f4nica localizada no hist\u00f3rico Old War Office, em Whitehall, Londres, que acompanhou parte dos pol\u00edticos e espi\u00f5es mais famosos da Gr\u00e3-Bretanha, de <span class=\"xn-person\">Winston Churchill<\/span> a <span class=\"xn-person\">Ian Fleming<\/span>. O edif\u00edcio hist\u00f3rico passou por uma transforma\u00e7\u00e3o monumental, e agora conta com 120 luxuosos quartos e su\u00edtes, 85 resid\u00eancias privadas espetaculares e 11 restaurantes e bares ultra elegantes. Um spa Guerlain exclusivo e instala\u00e7\u00f5es de bem-estar da PILLAR oferecer\u00e3o ades\u00f5es particulares para moradores locais interessados.<\/span><\/p>\n<p><b><span>Raffles Boston Back Bay Hotel &#038; Residences (meados de 2023)<\/span><\/b><span><br \/><\/br>O primeiro hotel Raffles na Am\u00e9rica do Norte abrir\u00e1 suas portas este ano, trazendo um novo n\u00edvel de eleg\u00e2ncia, glamour e aventura para a cidade hist\u00f3rica de <span class=\"xn-location\">Boston<\/span>. Localizado no prestigiado bairro de <span class=\"xn-location\">Back Bay<\/span>, o luxuoso hotel conta com um impressionante sky lobby de tr\u00eas andares, in\u00e9dito na cidade. O distinto edif\u00edcio de 35 andares oferece uma cole\u00e7\u00e3o \u00fanica de 147 quartos e 146 resid\u00eancias, com su\u00edtes pied-\u00e0-terre, moradias de um a tr\u00eas quartos, e coberturas magn\u00edficas.<\/span><\/p>\n<p><b><span>Raffles At Galaxy Macau (meados de 2023)<\/span><\/b><span><br \/><\/br>Uma adi\u00e7\u00e3o impressionante ao Galaxy Macau<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i1.wp.com\/s.w.org\/images\/core\/emoji\/12.0.0-1\/72x72\/2122.png?ssl=1\" alt=\"\u2122\" class=\"wp-smiley\" style=\"height: 1em; max-height: 1em;\" \/>, um resort de luxo integrado e de excel\u00eancia. O Raffles At Galaxy Macau apresentar\u00e1 um novo n\u00edvel de sofistica\u00e7\u00e3o e requinte em <span class=\"xn-location\">Macau<\/span>. Cada uma das 450 <i>su\u00edtes foi projetada como se fosse um luxuoso pal\u00e1cio moderno, com uma The Frame<\/i> da Samsung em todos os quartos, e os famosos mordomos da marca oferecendo um servi\u00e7o discreto e personalizado.<\/span><\/p>\n<p><b><span><span class=\"xn-person\">Domaine De La Reine Margot<\/span> &#8211; MGallery (meados de 2023)<\/span><\/b><span>Os<br \/><\/br>h\u00f3spedes ter\u00e3o uma sensa\u00e7\u00e3o acolhedora de requinte aqui no cora\u00e7\u00e3o do Jardin des Qui\u00e9tudes, \u00e0s portas de Paris. Originalmente<sup>,<\/sup> o monumento hist\u00f3rico do s\u00e9culo 17 era o lar da Rainha Marguerite de <span class=\"xn-location\">Valois<\/span>. Revitalizado pelo estimado designer <span class=\"xn-person\">Jean-Michel Wilmotte<\/span>, o novo <span class=\"xn-person\">Domaine De La Reine Margot<\/span> &#8211; MGallery combina o esplendor do velho mundo com o chique contempor\u00e2neo. Um suntuoso spa permite aos h\u00f3spedes desfrutar de momentos de autocuidado, enquanto uma horta e um pomar proporcionam beleza abundante ao ar livre. <\/span><\/p>\n<p><b><span>Sofitel Shanghai North Bund (final de 2023)<\/span><\/b><span>A <span class=\"xn-person\">Art de Vivre<\/span><br \/><\/br>francesa brilhar\u00e1 intensamente no deslumbrante hotel emblem\u00e1tico de 25 andares, que conta com 300 quartos e su\u00edtes opulentos com vistas excepcionais do famoso horizonte de Xangai. Os h\u00f3spedes v\u00e3o amar o bar no terra\u00e7o, que certamente se tornar\u00e1 um ponto de atra\u00e7\u00e3o do Bund, com suas vistas deslumbrantes do rio. O estilo franc\u00eas moderno combina a experi\u00eancia hoteleira com o Club Mill\u00e9sime, um luxuoso Spa da Sofitel, e uma academia ultramoderna Sofitel Fitness.<\/span><\/p>\n<p><b><span>MontAzure Lakeside Phuket &#8211; MGallery (final de 2023)<\/span><\/b><span><br \/><\/br>O primeiro MGallery Residences na Tail\u00e2ndia ter\u00e1 vista para as \u00e1guas turquesa e a vegeta\u00e7\u00e3o exuberante da praia <span class=\"xn-person\">Kamala Beach<\/span>, em <span class=\"xn-location\">Phuket<\/span>. O requintado resort estilo boutique convida os h\u00f3spedes para uma comunidade privada de 236 est\u00fadios espa\u00e7osos e resid\u00eancias de um quarto, cercados por jardins, lagos e fontes em cascata. O senso de bem-estar e autocuidado di\u00e1rio t\u00edpico do MGallery fazem parte da experi\u00eancia, com um pavilh\u00e3o de relaxamento, pista de corrida, plataforma de ioga, academia, clube, trilha natural, \u00e1rea de piscina familiar, bem como um restaurante elegante e um delicioso bar na piscina.<\/span><\/p>\n<p><b><span>HOT\u00c9IS LIFESTYLE (<span class=\"xn-location\">ENNISMORE<\/span>)<\/span><\/b>\u00a0<\/p>\n<p><i><span>A <span class=\"xn-location\">Ennismore<\/span> \u00e9 uma empresa de hospitalidade criativa com um coletivo global de marcas empreendedoras e criadas por fundadores com um prop\u00f3sito central. Ela faz a curadoria e gerencia propriedades e experi\u00eancias \u00fanicas em alguns dos destinos mais fascinantes do mundo. A Accor e a <span class=\"xn-location\">Ennismore<\/span> firmaram uma colabora\u00e7\u00e3o comercial em 2021 para criar a empresa de hospitalidade de lifestyle de crescimento mais r\u00e1pido do mundo. No pr\u00f3ximo ano, a <span class=\"xn-location\">Ennismore<\/span> abrir\u00e1 mais de 30 hot\u00e9is e resid\u00eancias de marca, dando continuidade \u00e0 tend\u00eancia deste ano de abrir, em m\u00e9dia, um novo hotel a cada duas semanas.<\/span><\/i><\/p>\n<p><b><span><span class=\"xn-person\">Maison Delano Paris<\/span> (in\u00edcio de 2023)<\/span><\/b><span><br \/><\/br>Localizado no centro do chiqu\u00e9rrimo 8th Arrondissement, o <span class=\"xn-person\">Maison Delano Paris<\/span> \u00e9 um o\u00e1sis dentro da movimentada cidade. Ocupando um edif\u00edcio com p\u00e1tio do s\u00e9culo XVIII na 4 Rue d&#8217;<span class=\"xn-location\">Anjou<\/span>, \u00e9 um lugar para conhecer conceitos culin\u00e1rios excepcionais e exclusivos do Chef <span class=\"xn-person\">Dani Garc\u00eda<\/span>, que tem tr\u00eas estrelas Michelin \u2014 uma nova perspectiva sobre bem-estar e momentos de curadoria exclusivos.<\/span><\/p>\n<p><b><span>Mama Shelter Rennes (in\u00edcio de 2023)<\/span><\/b><span>Localizado<br \/><\/br>centralmente a apenas alguns passos da Place des Lices e da famosa Rue de la Soif, o Mama Shelter Rennes ser\u00e1 lar do primeir\u00edssimo Mama Skin Spa. Transformando o cen\u00e1rio hoteleiro do Rennes com uma oferta totalmente nova, o hotel ter\u00e1 119 quartos, cinco esta\u00e7\u00f5es de trabalho, um restaurante, piscina, v\u00e1rios quartos de karaok\u00ea, bem como o primeiro bar no terra\u00e7o da cidade com vistas deslumbrantes das torres medievais.<\/span><\/p>\n<p><b><span>SO\/ Uptown Dubai (in\u00edcio de 2023)<\/span><\/b><span><br \/><\/br>In\u00e9dito no Oriente M\u00e9dio, o SO\/ oferece um mundo de moda e estilo vanguardistas. Localizado na hist\u00f3rica torre Uptown, uma maravilha arquitet\u00f4nica inspirada na forma e nas reflex\u00f5es de luz de um diamante, o SO\/ Uptown Dubai abrigar\u00e1 restaurantes e bares, um spa e piscina sublimes, e um sal\u00e3o de festas de destaque, juntamente com 188 quartos elegantes. Uma cole\u00e7\u00e3o exclusiva de 229 resid\u00eancias privadas tamb\u00e9m estar\u00e1 dispon\u00edvel, incluindo apartamentos de um, dois e tr\u00eas quartos, bem como apartamentos duplex de quatro quartos, todos com vistas permanentes do espetacular horizonte da cidade.<\/span><\/p>\n<p><b><span>21c Museum Hotel St. Louis (in\u00edcio de 2023)<br \/><\/br><\/span><\/b><span>O hist\u00f3rico marco renascentista de 10 andares de <span class=\"xn-location\">St. Louis<\/span> est\u00e1 entrando em uma nova era. O 21c est\u00e1 dando vida nova ao edif\u00edcio centen\u00e1rio com espa\u00e7os repletos de arte contempor\u00e2nea, programa\u00e7\u00e3o cultural voltada para a comunidade, alimentos e bebidas de origem local e, \u00e9 claro, com a hospitalidade que \u00e9 l\u00edder mundial. Honrando as ra\u00edzes do edif\u00edcio como um antigo n\u00facleo do YMCA, o 21c <span class=\"xn-location\">St. Louis<\/span> tamb\u00e9m contar\u00e1 com um clube atl\u00e9tico e de nata\u00e7\u00e3o completo.<\/span><\/p>\n<p><b><span>TRIBE Bangkok Sukhumvit 39 (in\u00edcio de 2023)<\/span><\/b><span><br \/><\/br>O centro social est\u00e1 no cora\u00e7\u00e3o do TRIBE Bangkok Sukhumvit 39. Confort\u00e1vel e funcional desde o projeto, ele tamb\u00e9m abriga uma cafeteria com lanches para viagem, caf\u00e9s de baristas durante o dia, e coquet\u00e9is exclusivos \u00e0 noite. Cada detalhe foi considerado para criar um lar longe de casa elegante e inteligente. Seja para ficar em forma ou para relaxar, os h\u00f3spedes do TRIBE podem aproveitar a academia, a piscina e o spa Onsen.<\/span><\/p>\n<p><b><span>Mondrian <span class=\"xn-location\">Singapore<\/span> (in\u00edcio de 2023)<\/span><\/b><span><br \/><\/br>Localizado no promissor bairro de Duxton Hill, a poucos passos do distrito financeiro da cidade, o Mondrian Singapore est\u00e1 situado entre as cafeterias mais modernas, restaurantes e bares de excel\u00eancia, e galerias de arte e boutiques independentes. Elevando-se acima das lojas hist\u00f3ricas e coloridas de Chinatown, o hotel est\u00e1 posicionado de modo a ter algumas das melhores vistas do horizonte da cidade.<\/span><\/p>\n<p><b><span>Rixos Qetaifan Island, <span class=\"xn-location\">Doha<\/span> (meados de 2023)<\/span><\/b><span><br \/><\/br>Com vista para o Golfo P\u00e9rsico, o novo resort Rixos Qetaifan Island oferece divers\u00e3o ilimitada para todas as idades. O Rixy Kids Club do hotel proporcionar\u00e1 um lugar feliz onde as crian\u00e7as poder\u00e3o fazer artes e artesanatos, fazer amigos e se divertir. Os adultos desfrutar\u00e3o das melhores f\u00e9rias relaxantes com o tradicional banho turco e luxuosas salas de tratamento de spa, clube esportivo exclusivo, e entretenimento noturno com apresenta\u00e7\u00f5es ao vivo de excel\u00eancia.<\/span><\/p>\n<p><b><span>The Hoxton, Charlottenburg (meados de 2023)<\/span><\/b><span><br \/><\/br>O Hoxton estar\u00e1 localizado em Charlottenburg, na Berlim Ocidental; uma \u00e1rea amada por sua cena gastron\u00f4mica ecl\u00e9tica e lojas de antiguidades, e a apenas alguns minutos da popular \u00e1rea comercial de Kurf\u00fcrstendamm. Instalado em um antigo hotel, o primeiro posto avan\u00e7ado da marca na Alemanha foi transformado com a ajuda do AIME Studios, o est\u00fadio de design pr\u00f3prio da <span class=\"xn-location\">Ennismore<\/span>. Inspirados no bairro \u2014 que ficava no centro do renascimento criativo da cidade durante a era de ouro dos anos 20 de Berlim \u2014, os 234 quartos do hotel ser\u00e3o decorados com formas inspiradas na <span class=\"xn-person\">Art Nouveau<\/span>, design expressivo e tons suaves.<\/span><\/p>\n<p><b><span>Mondrian Ibiza e Hyde Ibiza (meados de 2023)<\/span><\/b><span><br \/><\/br>A caminho da bela ilha de Ibiza pela primeira vez no ver\u00e3o de 2023 estar\u00e3o duas das marcas da <span class=\"xn-location\">Ennismore<\/span> \u2014 Mondrian e Hyde. Ambos os hot\u00e9is estar\u00e3o localizados no lado sudeste da ilha, na pitoresca Ba\u00eda de Cala Llonga, com amplas praias arenosas e colinas cobertas de pinheiros em ambos os lados. O Mondrian Ibiza ter\u00e1 154 quartos, enquanto o Hyde Ibiza ter\u00e1 409. Considerando as duas propriedades, haver\u00e1 nove restaurantes e bares, incluindo um beach club, todos com curadoria do est\u00fadio de conceito de alimentos e bebidas da <span class=\"xn-location\">Ennismore<\/span>, o Carte Blanched.<\/span><\/p>\n<p><b><span><span class=\"xn-person\">MAIS MARCAS<\/span>, MAIS HOT\u00c9IS, <span class=\"xn-person\">MAIS MERCADOS<\/span><\/span><\/b>\u00a0<\/p>\n<p><i><span>Os hot\u00e9is t\u00e3o esperados mencionados acima oferecem uma amostra idealista dos planos para 2023 da Accor nas categorias de luxo e lifestyle. No geral, a empresa abrir\u00e1 centenas de novos hot\u00e9is e resorts em todo o mundo atrav\u00e9s de seu crescente portf\u00f3lio, que conta com mais de 40 marcas. Aqui est\u00e3o mais algumas amostras para agu\u00e7ar o paladar dos viajantes.<\/span><\/i><\/p>\n<p><b><span>EUROPA<\/span><\/b>\u00a0<\/p>\n<p><b><span>greet hotel Paris Hippodrome De Vincennes (in\u00edcio de 2023)<\/span><\/b><span>Os hot\u00e9is<br \/><\/br>greet s\u00e3o defensores da mentalidade &#8220;fa\u00e7a o bem, sinta-se bem&#8221;, onde as boas a\u00e7\u00f5es alimentam bons sentimentos. No greet hotel Paris Hippodrome De Vincennes, os h\u00f3spedes ter\u00e3o uma experi\u00eancia \u00fanica de hospitalidade e design ecol\u00f3gico, come\u00e7ando com uma deliciosa bebida de boas-vindas e guloseimas fresquinhas de lojas locais. Nas confort\u00e1veis \u00e1reas sociais, os h\u00f3spedes se encontram, jogam jogos de tabuleiro e socializam em meio a um ambiente incr\u00edvel e mobili\u00e1rio bem reciclado.<\/span><\/p>\n<p><b><span>ibis Styles Copenhagen \u00d8restad, Dinamarca (in\u00edcio de 2023)<\/span><\/b><span>O<br \/><\/br>ibis Styles estreia na Dinamarca neste inverno. O novo hotel foi projetado para combinar a vida urbana com a serenidade da natureza \u2014 dois temas concretizados no design do hotel em forte e brilhante contraste. O elegante hotel est\u00e1 idealmente localizado dentro do vibrante distrito e ilha de Amager, perto do centro da cidade de Copenhague. Situado no popular projeto Nest45, o hotel fica em um centro atraente de escrit\u00f3rios e pequenas empresas.<\/span><\/p>\n<p><b><span>Swiss\u00f4tel <span class=\"xn-location\">Tbilisi<\/span>, Ge\u00f3rgia (meados de 2023)<\/span><\/b><span><br \/><\/br>O primeiro Swiss\u00f4tel na Ge\u00f3rgia estar\u00e1 localizado no centro da cidade antiga de Tibl\u00edssi. Os h\u00f3spedes se beneficiar\u00e3o de sua localiza\u00e7\u00e3o privilegiada no centro da cidade de Tibl\u00edssi, perto da Galeria Nacional e do Parlamento, e pr\u00f3ximo a tr\u00eas parques da cidade e pontos tur\u00edsticos importantes. O design interior criado por Sundukovy Sisters distingue-se pelos motivos e elementos decorativos florais, criando um o\u00e1sis de calma e natureza. O opulento restaurante e bar do terra\u00e7o, no 7\u00ba andar, oferece vistas fascinantes da cidade.<\/span><\/p>\n<p><b><span>Pullman Okol Resort Golf &#038; Spa, Bulg\u00e1ria (meados de 2023)<\/span><\/b><span>O hotel<br \/><\/br>Pullman inaugura na Bulg\u00e1ria em 2023. O hotel de 140 quartos e as 40 resid\u00eancias de marca est\u00e3o situados a apenas 30 km a sudeste da cidade de Sof\u00eda e a apenas 20 minutos de uma das maiores esta\u00e7\u00f5es de esqui da Bulg\u00e1ria \u2014 Borovets. Rodeado por um belo parque, o Pullman Okol Golf Resort &#038; Spa faz parte do projeto OKOL Lake Park, na orla do <span class=\"xn-person\">Lago Iskar<\/span>, a sudeste de S\u00f3fia. O design do hotel \u00e9 inspirado na natureza circundante e na heran\u00e7a cultural b\u00falgara.<\/span><\/p>\n<p><b><span>Adagio London Whitechapel (final de 2023)<\/span><\/b><span><br \/><\/br>Para os h\u00f3spedes que desejarem os servi\u00e7os \u00fateis de um hotel e a liberdade de viver como um morador local em um apartamento de bairro, o Adagio oferece o equil\u00edbrio perfeito entre ambos. Projetados para estadias mais longas, os 147 apartamentos equipados na Whitechapel Road, no leste de Londres, oferecer\u00e3o apartamentos de um ou dois quartos completos com cozinha. \u00c1reas comuns animadas criam uma atmosfera acolhedora e de conv\u00edvio que incentiva novas conex\u00f5es.<\/span><\/p>\n<p><b><span>Swiss\u00f4tel Resort Kolasin, <span class=\"xn-location\">Montenegro<\/span> (final de 2023)<\/span><\/b><span><br \/><\/br>A primeira propriedade da Accor em <span class=\"xn-location\">Montenegro<\/span> estar\u00e1 localizada a 1.600 metros acima do n\u00edvel do mar, em meio \u00e0s pitorescas pistas de esqui. O design do hotel de 116 quartos se integra ao ambiente natural, preservando a localiza\u00e7\u00e3o e capturando a ess\u00eancia da vitalidade natural do Swiss\u00f4tel. Base ideal para os f\u00e3s de esportes de inverno, a nova propriedade fica localizada dentro do resort K16, em Kolasin, junto \u00e0 magn\u00edfica cordilheira de Belasica \u2014 o destino perfeito para quem deseja aproveitar as pistas de ski.<\/span><\/p>\n<p><b><span>AS AM\u00c9RICAS<\/span><\/b>\u00a0<\/p>\n<p><b><span>Novotel Mexico City Centro Historico (final de 2023)<\/span><\/b><span><br \/><\/br>Novotel, uma das marcas de hot\u00e9is midscale mais conhecidas e confi\u00e1veis do mundo, est\u00e1 refor\u00e7ando sua presen\u00e7a na Cidade do M\u00e9xico com uma quarta propriedade \u2014 no hist\u00f3rico distrito central. No Novotel Mexico City Centro Historico, os viajantes a neg\u00f3cios descansar\u00e3o, enquanto as fam\u00edlias aproveitar\u00e3o um tempo de qualidade. Do acolhedor e descontra\u00eddo centro social multifuncional ao bar informal e quartos espa\u00e7osos, cada aspecto do hotel conta com um design moderno e elegante para criar uma atmosfera acolhedora e amig\u00e1vel.<\/span><\/p>\n<p><b><span><span class=\"xn-location\">CHINA<\/span><\/span><\/b>\u00a0<\/p>\n<p><b><span>M\u00f6venpick by Accor, <span class=\"xn-location\">Qingdao<\/span><\/span><\/b><span> <b>(final de 2023)<\/b><br \/><\/br>Esta mudan\u00e7a em uma marca cl\u00e1ssica \u00e9 \u00fanica para a <span class=\"xn-location\">China<\/span>, e ela abrir\u00e1 seu primeiro hotel na bela cidade costeira de <span class=\"xn-location\">Qingdao<\/span>, no leste da prov\u00edncia de <span class=\"xn-location\">Shandong<\/span>, coincidindo com o<sup>75\u00ba<\/sup> anivers\u00e1rio da marca M\u00f6venpick. Com base nas caracter\u00edsticas conhecidas e amadas da marca M\u00f6venpick e no patrim\u00f4nio su\u00ed\u00e7o, a<b><i> M\u00f6venpick by Accor <\/i><\/b>oferecer\u00e1 uma adapta\u00e7\u00e3o espec\u00edfica para a <span class=\"xn-location\">China<\/span> \u2014 personalizada para os interesses, gostos, cultura e prefer\u00eancias dos viajantes chineses.<\/span><\/p>\n<p><b><span>Grand Mercure Living Chengdu e Grand Mercure Chengdu (final de 2023)<\/span><\/b><span><br \/><\/br>Uma experi\u00eancia encantadora e convidativa aguarda no novo hotel Grand Mercure, em <span class=\"xn-location\">Chengdu<\/span>, e nas primeiras resid\u00eancias Grand Mercure Living, na <span class=\"xn-location\">China<\/span>. Viajantes e moradores se encantar\u00e3o com a ado\u00e7\u00e3o do Grand Mercure de tradi\u00e7\u00f5es culturais, culin\u00e1ria influenciada localmente e express\u00e3o art\u00edstica inspirada. Localizado dentro do Western Financial Innovation Center, os h\u00f3spedes do hotel e moradores das resid\u00eancias desfrutar\u00e3o da conveni\u00eancia de estar perto de tudo no distrito comercial da regi\u00e3o, com o conforto de retornar \u00e0 calorosa hospitalidade do Grand Mercure.<\/span><\/p>\n<p><b><span>\u00cdNDIA, ORIENTE M\u00c9DIO, \u00c1SIA E \u00c1FRICA<\/span><\/b>\u00a0<\/p>\n<p><b><span>Mercure Hotel Cairns (in\u00edcio de 2023)<\/span><\/b><span>O<br \/><\/br>Mercure chegar\u00e1 no principal destino de f\u00e9rias costeiras de Cairns, na Tropical North Queensland, com a abertura do Mercure Hotel Cairns. O novo hotel surge ap\u00f3s uma reforma e reformula\u00e7\u00e3o multimilion\u00e1ria. Cercado e inspirado pela natureza, o Mercure Hotel Cairns compreende 75 quartos espa\u00e7osos e um novo restaurante australiano moderno que serve os melhores produtos locais.<\/span><\/p>\n<p><b><span>Pullman Singapore Hill Street (meados de 2023)<\/span><\/b><span><br \/><\/br>O hotel de 342 quartos ser\u00e1 o primeiro Pullman de Singapura, com uma localiza\u00e7\u00e3o privilegiada na Hill Street, no cora\u00e7\u00e3o c\u00edvico e cultural da cidade. Atraindo pensadores progressistas e viajantes globais, o bar e o lounge executivo do hotel no terra\u00e7o oferecem vistas inspiradoras para Fort Canning, o Singapore River, e a St Andrew&#8217;s Cathedral. O lobby vibrante \u00e9 um espa\u00e7o fluido para trabalhar, jogar e se conectar com outras pessoas, enquanto o amplo espa\u00e7o de sa\u00fade e condicionamento f\u00edsico e a piscina oferecem experi\u00eancias inovadoras para o bem-estar.<\/span><\/p>\n<p><b><span>ibis Styles Bangkok Twin Towers (meados de 2023)<\/span><\/b><span><br \/><\/br>O maior hotel ibis Styles do mundo levar\u00e1 sua energia criativa e divertida para o centro de <span class=\"xn-location\">Bangkok<\/span>, a poucos passos do distrito financeiro, comercial, e dos pontos tur\u00edsticos favoritos, como MBK, Siam Paragon e Siam Discovery. Com mais de 600 quartos com design \u00fanico, o hotel moderno e econ\u00f4mico oferecer\u00e1 tr\u00eas restaurantes, salas de reuni\u00e3o, uma piscina ao ar livre, academia e spa \u2014 juntamente com alguns b\u00f4nus, para que cada estadia seja exclusiva e especial.<\/span><\/p>\n<p><b><span>Novotel New Delhi City Centre<\/span><\/b><span> <b>(meados de 2023)<\/b><br \/><\/br>Para viajantes que queiram relaxar e desacelerar, o Novotel New Delhi City Centre oferece um lugar calmo para desfrutar de um pouco de descanso em meio \u00e0 cidade movimentada. Os h\u00f3spedes podem apreciar uma x\u00edcara de ch\u00e1 enquanto desfrutam de um momento dedicado a si mesmos ou podem se divertir com seus entes queridos. Dos quartos modernos ao animado centro social e zona familiar infantil, o Novotel conta com espa\u00e7os <a target=\"_blank\"  href=\"hhttps:\/\/www.google.com\/search?client=firefox-b-e&q=studio+19+arquitetura\">contempor\u00e2neos<\/a>, confort\u00e1veis e intuitivos que permitem que os viajantes se dediquem ao que realmente importa.<\/span><\/p>\n<p><b><span>Mercure Tokyo Haneda (final de 2023)<\/span><\/b><span><br \/><\/br>O novo Mercure Tokyo Haneda ser\u00e1 um hotel associado ao Mercure Tokyo Ginza, proporcionando uma experi\u00eancia charmosa, din\u00e2mica e localmente aut\u00eantica de T\u00f3quio. Os centros sociais do Mercure oferecem din\u00e2micas durante todo o dia, com lugares flex\u00edveis para comer, beber, socializar ou trabalhar, enquanto as \u00e1reas comuns e os quartos do hotel s\u00e3o inspirados na cultura japonesa local e sua est\u00e9tica.<\/span><\/p>\n<p><b><span>Pullman Nairobi Upper Hill (meados de 2023)<\/span><\/b><span><br \/><\/br>Pullman, uma marca pioneira com um legado de inova\u00e7\u00e3o em hospitalidade, tem o prazer de oferecer um novo destino em meio \u00e0 agita\u00e7\u00e3o de Upper Hill, em Nair\u00f3bi. O novo hotel Pullman oferecer\u00e1 vistas inspiradoras do horizonte da cidade, com proximidade conveniente ao distrito financeiro da cidade, escrit\u00f3rios corporativos e embaixadas internacionais. Os h\u00f3spedes poder\u00e3o saborear drinques ao p\u00f4r do sol enquanto contemplam o famoso horizonte africano, ou poder\u00e3o sair cedo para descobrir as maravilhas de um saf\u00e1ri queniano no Parque Nacional de Nair\u00f3bi, que fica pr\u00f3ximo.<\/span><\/p>\n<p><b><span>SOBRE A ACCOR <\/span><\/b><\/p>\n<p><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=2711134867&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D89808200%26u%3Dhttps%253A%252F%252Fgroup.accor.com%252Fen%26a%3DAccor&#038;a=Accor\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>Accor<\/span><\/a><span> \u00e9 um grupo hoteleiro l\u00edder mundial composto por 5.300 propriedades e 10 mil espa\u00e7os para comer e beber em 110 pa\u00edses. O Grupo possui um dos ecossistemas de hospitalidade mais diversificados e totalmente integrados do setor, abrangendo mais de 40 marcas de hot\u00e9is de luxo, premium, midscale e econ\u00f4micos, espa\u00e7os de entretenimento e vida noturna, restaurantes e bares, resid\u00eancias privadas de marca, propriedades de acomoda\u00e7\u00e3o compartilhada, servi\u00e7os de concierge, espa\u00e7os de trabalho compartilhados e muito mais. A posi\u00e7\u00e3o incompar\u00e1vel da Accor em hospitalidade de lifestyle \u2014 uma das categorias de mais r\u00e1pido crescimento na ind\u00fastria \u2014 \u00e9 liderada pela <span class=\"xn-location\">Ennismore<\/span>, uma colabora\u00e7\u00e3o comercial na qual a Accor det\u00e9m participa\u00e7\u00e3o majorit\u00e1ria. A <span class=\"xn-location\">Ennismore<\/span> \u00e9 uma empresa de hospitalidade criativa com um coletivo global de marcas empreendedoras e criadas por fundadores com um prop\u00f3sito central. A Accor possui um portf\u00f3lio incompar\u00e1vel de marcas distintas e mais de 230 mil membros de equipe no mundo todo. Os membros se beneficiam do abrangente programa de fidelidade da empresa \u2014 <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=2672301434&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D2077415150%26u%3Dhttps%253A%252F%252Fall.accor.com%252F%26a%3DALL%2B-%2BAccor%2BLive%2BLimitless&#038;a=ALL+-+Accor+Live+Limitless\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>ALL &#8211; Accor Live Limitless<\/span><\/a><span> \u2014, um companheiro di\u00e1rio de lifestyle que oferece acesso a uma ampla variedade de recompensas, servi\u00e7os e experi\u00eancias. Por meio de seus compromissos globais com a sustentabilidade (como o alcance de zero emiss\u00f5es de gases do efeito estufa at\u00e9 2050, elimina\u00e7\u00e3o global de pl\u00e1sticos descart\u00e1veis na experi\u00eancia do h\u00f3spede em seus hot\u00e9is, etc.), e as iniciativas Accor Solidarity, RiiSE e ALL Heartist Fund, o Grupo est\u00e1 focado em impulsionar a\u00e7\u00f5es positivas atrav\u00e9s da \u00e9tica nos neg\u00f3cios, turismo respons\u00e1vel, sustentabilidade ambiental, engajamento da comunidade, diversidade e inclus\u00e3o. Fundada em 1967, a Accor SA est\u00e1 sediada na Fran\u00e7a e \u00e9 listada publicamente no Euronext Paris Stock Exchange (c\u00f3digo ISIN: FR0000120404) e no OTC Market (Ticker: ACCYY) nos Estados Unidos. Para saber mais, acesse <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=1626060860&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D3254255515%26u%3Dhttps%253A%252F%252Fgroup.accor.com%252Fen%26a%3Dgroup.accor.com&#038;a=group.accor.com\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>group.accor.com<\/span><\/a><span> ou acompanhe a Accor no <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=3742754936&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D2024928788%26u%3Dhttps%253A%252F%252Ftwitter.com%252FAccor%26a%3DTwitter&#038;a=Twitter\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>Twitter<\/span><\/a><span>,<\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=482508901&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D3425108132%26u%3Dhttps%253A%252F%252Fwww.facebook.com%252FaccorFR%252F%26a%3D%25C2%25A0Facebook&#038;a=+Facebook\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span> Facebook<\/span><\/a><span>, <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=588199186&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D1567860100%26u%3Dhttps%253A%252F%252Fwww.linkedin.com%252Fcompany%252Faccor%252F%26a%3DLinkedIn&#038;a=LinkedIn\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>LinkedIn<\/span><\/a><span>, <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=4132497519&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D1445525084%26u%3Dhttps%253A%252F%252Fwww.instagram.com%252Faccor%26a%3DInstagram&#038;a=Instagram\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>Instagram<\/span><\/a><span> e <\/span><a href=\"https:\/\/c212.net\/c\/link\/?t=0&#038;l=pt&#038;o=3737813-1&#038;h=171115045&#038;u=https%3A%2F%2Fc212.net%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D3737813-1%26h%3D1148590054%26u%3Dhttps%253A%252F%252Fwww.tiktok.com%252F%2540accor%253Flang%253Den%26a%3DTikTok.&#038;a=TikTok.\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><span>TikTok.<\/span><\/a><\/p>\n<p><span>Contatos para a imprensa: Charlotte Thouvard, <a href=\"mailto:charlotte.thouvard@accor.com\" rel=\"nofollow\">charlotte.thouvard@accor.com<\/a>; <span class=\"xn-person\">Mike Taylor<\/span>, <a href=\"mailto:mike.taylor@accor.com\" rel=\"nofollow\">mike.taylor@accor.com<\/a>; Line Crieloue, <a href=\"mailto:line.crieloue@accor.com\" rel=\"nofollow\">line.crieloue@accor.com<\/a><\/span><\/p>\n<p>FONTE Accor<\/p>\n<\/div>\n<p><!-- Este texto tem o apoio do Sistema ECOMPARE de lojas virtuais <a rel=\"nofollow\" href=\"https:\/\/prnewswire.com.br\/releases\/lista-da-accor-com-as-principais-inauguracoes-de-hoteis-em-2023\/\">Lista da Accor com as principais inaugura\u00e7\u00f5es de hot\u00e9is em 2023<\/a> apareceu primeiro em <a rel=\"nofollow\" href=\"https:\/\/prnewswire.com.br\">PR Newswire<\/a>.<\/p>&nbsp;&nbsp;\n","protected":false},"excerpt":{"rendered":"<p>UM RESUMO DAS PR\u00d3XIMAS PROPRIEDADES DO PORTF\u00d3LIO MAIS DIVERSO DO MUNDO DE MARCAS HOTELEIRAS PARIS,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[727],"tags":[],"class_list":["post-60288","post","type-post","status-publish","format-standard","hentry","category-noticias","wpcat-727-id"],"_links":{"self":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/60288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/comments?post=60288"}],"version-history":[{"count":0,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/60288\/revisions"}],"wp:attachment":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/media?parent=60288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/categories?post=60288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/tags?post=60288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}