{"id":75537,"date":"2019-08-13T18:41:08","date_gmt":"2019-08-13T21:41:08","guid":{"rendered":"https:\/\/verde-amarelo.net\/verdeamarelo\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019\/"},"modified":"2019-08-13T18:41:08","modified_gmt":"2019-08-13T21:41:08","slug":"valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019","status":"publish","type":"post","link":"https:\/\/verde-amarelo.net\/verdeamarelo\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019\/","title":{"rendered":"Valor da Produ\u00e7\u00e3o Agropecu\u00e1ria deve atingir R$ 603,4 bilh\u00f5es em 2019"},"content":{"rendered":"<div><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2019\/08\/valor-da-producao-agropecuaria-deve-atingir-r-6034-bilhoes-em-2019.jpg?ssl=1\" class=\"ff-og-image-inserted\"><\/div>\n<p>O valor \u00e9 o segundo maior alcan\u00e7ado pela agropecu\u00e1ria em 30 anos. O primeiro ocorreu em 2017, com R$ 607,9 bilh\u00f5es.<\/p>&nbsp;&nbsp;\n<div id=\"viewlet-below-content-title\" readability=\"32\">\n<p><span class=\"documentPublished\"><span>publicado<\/span>: <span property=\"rnews:datePublished\">13\/08\/2019 15h25<\/span><\/span> <span class=\"documentModified\"><span>\u00faltima modifica\u00e7\u00e3o<\/span>: <span property=\"rnews:dateModified\">13\/08\/2019 15h41<\/span><\/span><\/p>\n<\/div>\n<div property=\"rnews:articleBody\" readability=\"109.303854875\">\n<p>O Valor Bruto da Produ\u00e7\u00e3o Agropecu\u00e1ria (VBP) deve atingir R$ 603,4 bilh\u00f5es neste ano, com base nas informa\u00e7\u00f5es de julho, 1,2% acima do obtido em 2018 (R$ 596,1 bilh\u00f5es). O valor \u00e9 o segundo maior alcan\u00e7ado pela agropecu\u00e1ria em 30 anos. O primeiro ocorreu em&nbsp; 2017, com R$ 607,9 bilh\u00f5es.<\/p>&nbsp;&nbsp;\n<p>As principais lavouras representaram R$ 399 bilh\u00f5es, e a pecu\u00e1ria, R$ 204,4 bilh\u00f5es. A pecu\u00e1ria apresenta varia\u00e7\u00e3o positiva de 4,5% e as lavouras tend\u00eancia de redu\u00e7\u00e3o.<\/p>&nbsp;&nbsp;\n<p>\u201cEssas tend\u00eancias observadas devem permanecer at\u00e9 o final do ano, pois a safra deste ano est\u00e1 praticamente encerrada\u201d, observa o coordenador-geral de Avalia\u00e7\u00e3o de Pol\u00edticas e Informa\u00e7\u00e3o, da Secretaria de Pol\u00edtica Agr\u00edcola, do Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento, Jos\u00e9 Garcia Gasques.<\/p>&nbsp;&nbsp;\n<p><strong><a title href=\"http:\/\/www.agricultura.gov.br\/noticias\/valor-da-producao-agropecuaria-e-de-r-603-4-bilhoes-em-2019\/201907ValorBrutodaProduoRegionalporUF.xlsx\" class=\"internal-link\" target=\"_blank\" rel=\"noopener\">&gt;&gt; Veja aqui dados do VBP<\/a><\/strong><\/p>\n<p>Os melhores resultados s\u00e3o observados nas culturas do algod\u00e3o, com aumento real de 16,6% no VBP, amendoim (14,3%), da banana (20,5%), da batata inglesa (117,8%), do feij\u00e3o (64,9%), do cacau (1,9%), da laranja (8,1%), da mamona (34,9%), do milho (22,9%), do tomate (19,6%) e do trigo (8,2%).<\/p>&nbsp;&nbsp;\n<p>O que mais se destaca nos resultados, al\u00e9m do elevado acr\u00e9scimo de valor em algumas lavouras, \u00e9 o desempenho do milho por meio do excepcional valor obtido, atingindo R$ 60,4 bilh\u00f5es de VBP. Torna-se, entre as lavouras, a segunda atividade mais importante depois da soja (R$ 129 bilh\u00f5es).<\/p>&nbsp;&nbsp;\n<p>O desempenho do milho 2\u00aa safra, conforme apresentado pela Conab e pelo IBGE nos relat\u00f3rios deste m\u00eas, foram decisivos para os resultados deste ano. A produtividade cresceu 25,8% em rela\u00e7\u00e3o a 2018. Do mesmo modo, explica Gasques, \u201ca safra recorde de gr\u00e3os prevista em 241,3 milh\u00f5es de toneladas foi essencial para o crescimento da agropecu\u00e1ria como um todo\u201d.<\/p>&nbsp;&nbsp;\n<p>Na pecu\u00e1ria, destacam-se os valores da carne de frango (13,4%) e de su\u00ednos (9,3%), e por \u00faltimo a carne bovina, com aumento de 1,3%.<\/p>&nbsp;&nbsp;\n<p><strong><a title href=\"http:\/\/www.agricultura.gov.br\/noticias\/valor-da-producao-agropecuaria-e-de-r-603-4-bilhoes-em-2019\/201907ValorBrutodaProduoPrincipaisProdutosAgropecurios.xlsx\" class=\"internal-link\" target=\"_blank\" rel=\"noopener\">&gt;&gt; Veja aqui o VBP dos principais produtos agropecu\u00e1rios<\/a><\/strong><\/p>\n<p>Um grupo importante de produtos tem apresentado desempenhos desfavor\u00e1veis em rela\u00e7\u00e3o ao ano passado. O coordenador do estudo cita o arroz, caf\u00e9, cana-de-a\u00e7\u00facar, mandioca, soja e uva. A participa\u00e7\u00e3o desses produtos no valor das lavouras \u00e9 de 58%. No caso da soja, cana-de-a\u00e7\u00facar e do caf\u00e9, principalmente, os pre\u00e7os t\u00eam sido respons\u00e1veis pelo desempenho negativo.<\/p>&nbsp;&nbsp;\n<p>Os resultados regionais mostram novamente que Mato Grosso, S\u00e3o Paulo, Paran\u00e1, Minas Gerais e Rio Grande do Sul lideram a gera\u00e7\u00e3o de valor da produ\u00e7\u00e3o agropecu\u00e1ria no pa\u00eds.<\/p>&nbsp;&nbsp;\n<p><strong>Mais informa\u00e7\u00f5es \u00e0 imprensa:<br \/><\/strong>Coordena\u00e7\u00e3o-geral de Comunica\u00e7\u00e3o Social<br \/>Inez De Podest\u00e0<br \/><a href=\"mailto:imprensa@agricultura.gov.br\">imprensa@agricultura.gov.br<\/a><\/p>\n<\/div>\n<p><a href=\"http:\/\/www.agricultura.gov.br\/noticias\/valor-da-producao-agropecuaria-e-de-r-603-4-bilhoes-em-2019\" target=\"_blank\" rel=\"noopener\">Mais em http:\/\/www.agricultura.gov.br\/noticias\/valor-da-producao-agropecuaria-e-de-r-603-4-bilhoes-em-2019<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O valor \u00e9 o segundo maior alcan\u00e7ado pela agropecu\u00e1ria em 30 anos. O primeiro ocorreu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[727],"tags":[],"class_list":["post-75537","post","type-post","status-publish","format-standard","hentry","category-noticias","wpcat-727-id"],"_links":{"self":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/75537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/comments?post=75537"}],"version-history":[{"count":0,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/75537\/revisions"}],"wp:attachment":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/media?parent=75537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/categories?post=75537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/tags?post=75537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}