{"id":78327,"date":"2020-06-23T00:10:41","date_gmt":"2020-06-23T03:10:41","guid":{"rendered":"https:\/\/verde-amarelo.net\/verdeamarelo\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia\/"},"modified":"2024-04-25T18:25:16","modified_gmt":"2024-04-25T21:25:16","slug":"compliance-um-aliado-em-tempos-de-pandemia","status":"publish","type":"post","link":"https:\/\/verde-amarelo.net\/verdeamarelo\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia\/","title":{"rendered":"Compliance: um aliado em tempos de pandemia"},"content":{"rendered":"<div class=\"image-full\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" width=\"278\" height=\"268\" alt class=\"attachment-full size-full wp-post-image lazyload\" fifu-data-src=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1\"><noscript><\/p>\n<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" width=\"278\" height=\"268\" fifu-data-src=\"https:\/\/i2.wp.com\/www.truckbrasil.com.br\/wp\/wp-content\/uploads\/2020\/06\/compliance-um-aliado-em-tempos-de-pandemia.jpg?ssl=1\" class=\"attachment-full size-full wp-post-image\" alt><\/p>\n<p><\/noscript><\/div>\n<p><em><strong>Por Akira Otsuka \u2013&nbsp;<\/strong><\/em><\/p>\n<p>O per\u00edodo de isolamento social instaurado em decorr\u00eancia da dissemina\u00e7\u00e3o do novo coronav\u00edrus no Brasil vem impactando opera\u00e7\u00f5es de empresas em diferentes segmentos, que buscam equilibrar a prote\u00e7\u00e3o do caixa, a perenidade do neg\u00f3cio e a preserva\u00e7\u00e3o dos empregos. Analisando o cen\u00e1rio, em um evento promovido em maio pela C\u00e2mara Americana de Com\u00e9rcio para o Brasil (Amcham), especialistas salientaram que o momento atual da crise provocada pela pandemia ser\u00e1 um grande teste para as \u00e1reas de compliance \u2013 setor que visa principalmente estabelecer um sistema de controle interno, para proporcionar maior seguran\u00e7a perante o mercado.<\/p>&nbsp;&nbsp;\n<p>Nos \u00faltimos anos, empresas brasileiras ampliaram o investimento nessa \u00e1rea, com a\u00e7\u00f5es tra\u00e7adas para garantir rela\u00e7\u00f5es \u00e9ticas e transparentes entre empresas e, principalmente, o Poder P\u00fablico. O compliance \u00e9 uma ferramenta atual e est\u00e1vel, para que a corpora\u00e7\u00e3o preserve sua integridade e resili\u00eancia, assim como a de seus colaboradores e da alta administra\u00e7\u00e3o.<\/p>&nbsp;&nbsp;\n<p>E como a pandemia impacta essa estabilidade? O desligamento de colaboradores; a redu\u00e7\u00e3o na remunera\u00e7\u00e3o; a adapta\u00e7\u00e3o de contrato com fornecedores; o investimento pontual em m\u00e1scaras, \u00e1lcool em gel e equipamentos de seguran\u00e7a voltados \u00e0 sa\u00fade; e a realiza\u00e7\u00e3o de a\u00e7\u00f5es sociais, como doa\u00e7\u00f5es, s\u00e3o exemplos de atua\u00e7\u00f5es que podem colocar a integridade da empresa em cheque neste per\u00edodo. Qualquer mudan\u00e7a que n\u00e3o seja devidamente registrada, dentro das conformidades e pol\u00edticas da empresa, com transpar\u00eancia e respeito aos princ\u00edpios legais, corre o risco de ser alvo de irregularidades.<\/p>&nbsp;&nbsp;\n<p>Neste per\u00edodo de incertezas, algumas empresas consideraram o desligamento das atividades das \u00e1reas de compliance, por n\u00e3o reconhecerem a grande essencialidade do departamento dentro de uma empresa. Mas o resultado \u00e9 bem o contr\u00e1rio: as empresas com estes setores bem estruturados podem passar por este momento com mais tranquilidade, com ci\u00eancia dos protocolos que devem ser seguidos para preservar a sua integridade. J\u00e1 as companhias que ainda n\u00e3o tinham desenvolvido essa \u00e1rea, estar\u00e3o mais vulner\u00e1veis \u00e0s irregularidades e ter\u00e3o trabalho redobrado para correr atr\u00e1s do preju\u00edzo.<\/p>&nbsp;&nbsp;\n<p>Como a pandemia da Covid-19 tem mantido algumas pessoas em suas casas, praticando o trabalho remoto, as companhias ter\u00e3o que encontrar uma solu\u00e7\u00e3o para seguir os protocolos \u00e0 dist\u00e2ncia. Uma estrat\u00e9gia adotada \u00e9 o uso ampliado da tecnologia digital, que departamentos podem utilizar para se comunicarem com seus stakeholders. Um exemplo \u00e9 a plataforma ClickCompliance, um software em nuvem com possibilidade de acesso remoto. A solu\u00e7\u00e3o \u00e9 respons\u00e1vel pela gest\u00e3o do programa em quatro frentes: gest\u00e3o de pol\u00edticas e documentos; canal de den\u00fancias; treinamentos; e compliance bot de atendimento, que \u00e9 um programa de computador respons\u00e1vel por automatizar procedimentos. Outros canais como TV corporativa, WhatsApp e e-mail tamb\u00e9m s\u00e3o alternativas eficazes para complementar as estrat\u00e9gias neste per\u00edodo.<\/p>&nbsp;&nbsp;\n<p>O departamento de compliance trabalha para que a empresa se adeque e cumpra as normas dos \u00f3rg\u00e3os reguladores, como tamb\u00e9m as normas internas elaboradas pela pr\u00f3pria companhia. O programa favorece a transpar\u00eancia, justi\u00e7a, sustentabilidade do neg\u00f3cio e muitos outros benef\u00edcios que promovem o fortalecimento e desenvolvimento da organiza\u00e7\u00e3o. \u00c9 uma estrat\u00e9gia essencial para assegurar a continuidade dos neg\u00f3cios em um cen\u00e1rio de incertezas e adequa\u00e7\u00f5es.<\/p>&nbsp;&nbsp;\n<p><em><strong>*Akira Otsuka \u00e9 Diretor de Risco e Compliance do Grupo A.Yoshii Engenharia<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Akira Otsuka \u2013&nbsp; O per\u00edodo de isolamento social instaurado em decorr\u00eancia da dissemina\u00e7\u00e3o do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[8717],"tags":[3774,6530,1145,2490,785,3836,370,2494,1874,1111,1676,735,1825,2989,3843,6570,2722,767,2994,2631,3895,4250,4015,792,2192,807,793,3340,772,3755,2332,8268,3897,4414,2008,39,6531,8217,2341,774,1223,1773,4383,457,219,2025,6532,280,1839,2280,1447,282,32,4759,2538,2915,3548,1438,1531,778,3265,1366,1515,1791,8571,2923,3710,3572,3331,4148,1796,2812,1619,1191,209,2570,1459,3308,1776,1967,42,3299,152,2991,1542,990],"class_list":["post-78327","post","type-post","status-publish","format-standard","hentry","category-artigos-de-opiniao","tag-alcool","tag-a-yoshii","tag-acoes","tag-alta","tag-artigos","tag-assim","tag-atendimento","tag-atividades","tag-bem","tag-beneficios","tag-bot","tag-brasil","tag-caixa","tag-canais","tag-canal","tag-ciencia","tag-colaboradores","tag-comercio","tag-companhia","tag-companhias","tag-computador","tag-contrato","tag-controle","tag-coronavirus","tag-covid","tag-covid-19","tag-crise","tag-desenvolvimento","tag-digital","tag-diretor","tag-doacoes","tag-documentos","tag-e","tag-empregos","tag-empresa","tag-empresas","tag-engenharia","tag-equipamentos","tag-essencial","tag-estrategia","tag-evento","tag-ferramenta","tag-fornecedores","tag-gel","tag-gestao","tag-grupo","tag-grupo-a-yoshii","tag-investimento","tag-isolamento","tag-isolamento-social","tag-justica","tag-mascaras","tag-mercado","tag-momento","tag-mudanca","tag-negocio","tag-nuvem","tag-operacoes","tag-organizacao","tag-pandemia","tag-publico","tag-pessoas","tag-plataforma","tag-prejuizo","tag-preservacao","tag-programa","tag-protecao","tag-reducao","tag-remuneracao","tag-resiliencia","tag-resultado","tag-risco","tag-saude","tag-seguranca","tag-setor","tag-setores","tag-sistema","tag-social","tag-software","tag-solucao","tag-tecnologia","tag-teste","tag-trabalho","tag-tv","tag-visa","tag-whatsapp","wpcat-8717-id"],"_links":{"self":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/78327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/comments?post=78327"}],"version-history":[{"count":0,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/posts\/78327\/revisions"}],"wp:attachment":[{"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/media?parent=78327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/categories?post=78327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verde-amarelo.net\/verdeamarelo\/wp-json\/wp\/v2\/tags?post=78327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}